{"id":1649,"date":"2025-01-08T19:12:37","date_gmt":"2025-01-08T18:12:37","guid":{"rendered":"https:\/\/bitacoraenlared.es\/chicas\/?p=1649"},"modified":"2025-01-10T19:34:45","modified_gmt":"2025-01-10T18:34:45","slug":"las-guardamos-dentro-de-nuestros-ojos","status":"publish","type":"post","link":"https:\/\/bitacoraenlared.es\/chicas\/las-guardamos-dentro-de-nuestros-ojos\/","title":{"rendered":"Las guardamos dentro de nuestros ojos"},"content":{"rendered":"<p><a href=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/34c4c4fb-a0d1-4c8e-9963-3e12c9e92603_5bb37a.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1650\" src=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/34c4c4fb-a0d1-4c8e-9963-3e12c9e92603_5bb37a.webp\" alt=\"\" width=\"800\" height=\"1066\" srcset=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/34c4c4fb-a0d1-4c8e-9963-3e12c9e92603_5bb37a.webp 650w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/34c4c4fb-a0d1-4c8e-9963-3e12c9e92603_5bb37a-225x300.webp 225w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/34c4c4fb-a0d1-4c8e-9963-3e12c9e92603_5bb37a-520x693.webp 520w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/633214f0-6ddb-48b1-88f2-59b49a60c3a8_0037a3.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1651\" src=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/633214f0-6ddb-48b1-88f2-59b49a60c3a8_0037a3.webp\" alt=\"\" width=\"800\" height=\"1066\" srcset=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/633214f0-6ddb-48b1-88f2-59b49a60c3a8_0037a3.webp 650w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/633214f0-6ddb-48b1-88f2-59b49a60c3a8_0037a3-225x300.webp 225w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/633214f0-6ddb-48b1-88f2-59b49a60c3a8_0037a3-520x693.webp 520w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/599995f9-2d72-41aa-9804-cb8ad7a7679c_6a047a.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1652\" src=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/599995f9-2d72-41aa-9804-cb8ad7a7679c_6a047a.webp\" alt=\"\" width=\"800\" height=\"993\" srcset=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/599995f9-2d72-41aa-9804-cb8ad7a7679c_6a047a.webp 650w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/599995f9-2d72-41aa-9804-cb8ad7a7679c_6a047a-242x300.webp 242w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/599995f9-2d72-41aa-9804-cb8ad7a7679c_6a047a-520x646.webp 520w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/91403b11-9de9-49f7-b170-78a6187ffcb8_f4a60c.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1653\" src=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/91403b11-9de9-49f7-b170-78a6187ffcb8_f4a60c.webp\" alt=\"\" width=\"800\" height=\"1066\" srcset=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/91403b11-9de9-49f7-b170-78a6187ffcb8_f4a60c.webp 650w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/91403b11-9de9-49f7-b170-78a6187ffcb8_f4a60c-225x300.webp 225w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/91403b11-9de9-49f7-b170-78a6187ffcb8_f4a60c-520x693.webp 520w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/8383f021-3e05-4e83-a5d4-60ab19ae4603.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1654\" src=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/8383f021-3e05-4e83-a5d4-60ab19ae4603.webp\" alt=\"\" width=\"800\" height=\"1200\" srcset=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/8383f021-3e05-4e83-a5d4-60ab19ae4603.webp 650w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/8383f021-3e05-4e83-a5d4-60ab19ae4603-200x300.webp 200w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/8383f021-3e05-4e83-a5d4-60ab19ae4603-520x780.webp 520w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/45y.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1655\" src=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/45y.webp\" alt=\"\" width=\"800\" height=\"988\" srcset=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/45y.webp 650w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/45y-243x300.webp 243w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/45y-520x642.webp 520w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><br \/>\n<a href=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469099522_548278364836500_6691899800106533112_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1658\" src=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469099522_548278364836500_6691899800106533112_n.jpg\" alt=\"\" width=\"800\" height=\"1028\" srcset=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469099522_548278364836500_6691899800106533112_n.jpg 526w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469099522_548278364836500_6691899800106533112_n-233x300.jpg 233w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469099522_548278364836500_6691899800106533112_n-520x668.jpg 520w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469343916_1898694163989292_7406305984975441819_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1659\" src=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469343916_1898694163989292_7406305984975441819_n.jpg\" alt=\"\" width=\"800\" height=\"1030\" srcset=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469343916_1898694163989292_7406305984975441819_n.jpg 800w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469343916_1898694163989292_7406305984975441819_n-233x300.jpg 233w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469343916_1898694163989292_7406305984975441819_n-795x1024.jpg 795w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469343916_1898694163989292_7406305984975441819_n-768x989.jpg 768w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469343916_1898694163989292_7406305984975441819_n-520x670.jpg 520w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469488571_554175857420622_1993508906461031599_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1660\" src=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469488571_554175857420622_1993508906461031599_n.jpg\" alt=\"\" width=\"800\" height=\"1070\" srcset=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469488571_554175857420622_1993508906461031599_n.jpg 800w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469488571_554175857420622_1993508906461031599_n-224x300.jpg 224w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469488571_554175857420622_1993508906461031599_n-766x1024.jpg 766w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469488571_554175857420622_1993508906461031599_n-768x1027.jpg 768w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469488571_554175857420622_1993508906461031599_n-520x696.jpg 520w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469532858_554176127420595_8279526358868819456_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1661\" src=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469532858_554176127420595_8279526358868819456_n.jpg\" alt=\"\" width=\"800\" height=\"1242\" srcset=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469532858_554176127420595_8279526358868819456_n.jpg 720w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469532858_554176127420595_8279526358868819456_n-193x300.jpg 193w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469532858_554176127420595_8279526358868819456_n-659x1024.jpg 659w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469532858_554176127420595_8279526358868819456_n-520x807.jpg 520w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469533993_122149347518321641_6612517488551670274_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1662\" src=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469533993_122149347518321641_6612517488551670274_n.jpg\" alt=\"\" width=\"800\" height=\"957\" srcset=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469533993_122149347518321641_6612517488551670274_n.jpg 800w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469533993_122149347518321641_6612517488551670274_n-251x300.jpg 251w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469533993_122149347518321641_6612517488551670274_n-768x919.jpg 768w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469533993_122149347518321641_6612517488551670274_n-520x622.jpg 520w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469548475_1273363674088024_1383995092816464373_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1663\" src=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469548475_1273363674088024_1383995092816464373_n.jpg\" alt=\"\" width=\"800\" height=\"1246\" srcset=\"https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469548475_1273363674088024_1383995092816464373_n.jpg 800w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469548475_1273363674088024_1383995092816464373_n-193x300.jpg 193w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469548475_1273363674088024_1383995092816464373_n-657x1024.jpg 657w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469548475_1273363674088024_1383995092816464373_n-768x1196.jpg 768w, https:\/\/bitacoraenlared.es\/chicas\/wp-content\/uploads\/sites\/2\/2025\/01\/469548475_1273363674088024_1383995092816464373_n-520x810.jpg 520w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1655,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-1649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chicas"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[1],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"_links":{"self":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts\/1649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/comments?post=1649"}],"version-history":[{"count":3,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts\/1649\/revisions"}],"predecessor-version":[{"id":1664,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts\/1649\/revisions\/1664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/media\/1655"}],"wp:attachment":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/media?parent=1649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/categories?post=1649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/tags?post=1649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}