{"id":2160,"date":"2025-04-28T13:12:08","date_gmt":"2025-04-28T11:12:08","guid":{"rendered":"https:\/\/bitacoraenlared.es\/chicas\/?p=2160"},"modified":"2025-04-24T13:20:19","modified_gmt":"2025-04-24T11:20:19","slug":"cinco-historias-de-asesinos-en-serie-tan-macabras-que-llegaron-al-cine","status":"publish","type":"post","link":"https:\/\/bitacoraenlared.es\/chicas\/cinco-historias-de-asesinos-en-serie-tan-macabras-que-llegaron-al-cine\/","title":{"rendered":"Cinco historias de asesinos en serie tan macabras que llegaron al cine"},"content":{"rendered":"<p>Cuando\u00a0<em><a href=\"https:\/\/hipertextual.com\/2024\/08\/5-peliculas-muy-retorcidas-para-ver-si-te-gusto-longlegs\">El silencio de los corderos<\/a><\/em>\u00a0se estren\u00f3 en 1991, caus\u00f3 revuelo. No solo porque\u00a0<a href=\"https:\/\/hipertextual.com\/2024\/09\/5-peliculas-de-terror-psicologico-que-jugaran-con-tu-mente\">Jonathan Demme<\/a>\u00a0logr\u00f3 captar el aire siniestro y violento del<a href=\"https:\/\/www.barnesandnoble.com\/w\/the-silence-of-the-lambs-thomas-harris\/1100356121\">\u00a0libro<\/a>\u00a0de Thomas Harris que adapta. Tambi\u00e9n, porque la forma en que explor\u00f3 en las muertes perpetradas por el criminal ficticio Buffalo Bill (Ted Levine) revolucion\u00f3 el g\u00e9nero de pel\u00edculas basadas en asesinos en serie. El director convirti\u00f3 a los asesinatos y a las v\u00edctimas, en una hoja de ruta para comprender la salvaje mente del personaje. Pero mucho m\u00e1s, al mostrar la forma en que el FBI, a trav\u00e9s de la figura de Clarice Starling (<a href=\"https:\/\/hipertextual.com\/2024\/02\/true-detective-4x04-final-explicado-noche-polar\">Jodie Foster<\/a>)\u00a0<strong>analizaba las pistas y huellas a su paso.<\/strong><\/p>\n<p>De hecho, buena parte del impacto de la pel\u00edcula, estuvo en explorar en las t\u00e9cnicas de<a href=\"https:\/\/le.fbi.gov\/science-and-lab\/behavioral-analysis\">\u00a0la Unidad de an\u00e1lisis de conducta<\/a>\u00a0en Quantico (Virginia). Y en particular, el c\u00f3mo se llevan a cabo las investigaciones alrededor de los criminales m\u00e1s peligrosos. Por lo que uno de los elementos m\u00e1s intrigantes, fue profundizar en el comportamiento de Buffalo Bill. Eso, debido a que, de la misma manera que el libro en el que se basa, el personaje de la ficci\u00f3n mezcl\u00f3 conductas de algunos homicidas. Entre ellos,\u00a0<a href=\"https:\/\/hipertextual.com\/2025\/01\/los-5-contenidos-mas-controvertidos-que-puedes-ver-en-netflix\">Ted Bundy<\/a>, Gary Heidnik,\u00a0<a href=\"https:\/\/hipertextual.com\/2024\/10\/cinco-peliculas-terrorificas-que-se-basan-en-hechos-documentados\">Ed Gein<\/a>\u00a0y Edmund Kemper. Una decisi\u00f3n de argumento\u00a0<strong>que convirti\u00f3 a la cinta en una de las m\u00e1s t\u00e9tricas y tensas de las \u00faltimas d\u00e9cadas.<\/strong><\/p>\n<p>Pero no es la \u00fanica cinta que incluy\u00f3 elementos ver\u00eddicos en su trama para hacer m\u00e1s cre\u00edble o narrar hechos de naturaleza con total precisi\u00f3n. Cinco historias de asesinos en serie que llegaron al cine casi de manera \u00edntegra. De un homicida que aterroriz\u00f3 Alaska en la d\u00e9cada de 1980 hasta un cruel criminal en Corea del Sur, que logr\u00f3 evitar ser capturado durante a\u00f1os. Una selecci\u00f3n de las historias m\u00e1s perversas y atroces que\u00a0<strong>el cine contempor\u00e1neo tiene para reflexionar sobre el mal de la naturaleza humana.<\/strong><\/p>\n<h2 id=\"h-caza-al-asesino-prime-nbsp-video-nbsp\" class=\"wp-block-heading has-text-align-center\">Caza al asesino (Prime Video)<\/h2>\n<p>En 2013, el director Scott Walker explor\u00f3 en los cr\u00edmenes de un asesino en medio del crudo invierno perpetuo de Alaska. Caza al asesino, sigue al detective Jack Halcombe (<a href=\"https:\/\/hipertextual.com\/2024\/05\/nicolas-cage-sera-spider-man-noir-en-una-serie-live-action\">Nicolas Cage<\/a>), a cargo de una compleja investigaci\u00f3n para descubrir al hombre detr\u00e1s del asesinato de 17 mujeres. Pero, gradualmente, descubrir\u00e1 que m\u00e1s all\u00e1 del caso, se encuentra\u00a0<strong>una mente criminal que juega de manera macabra con pistas y huellas.<\/strong><\/p>\n<p>En especial, porque Robert Hansen (<a href=\"https:\/\/hipertextual.com\/2023\/10\/5-grandes-adaptaciones-de-la-obra-de-edgar-allan-poe-que-puedes-ver-ahora-mismo-en-streaming\">John Cusack<\/a>), utiliza lo m\u00e1s salvaje y complicado del territorio no solo para ocultarse. Tambi\u00e9n, para manipular cualquier pista biol\u00f3gica que la polic\u00eda pueda encontrar en las escenas del crimen. Un giro de los acontecimientos que obligar\u00e1 a\u00a0<strong>Jack a emplearse a fondo para detener la carnicer\u00eda que el asesino deja a su paso.\u00a0<\/strong><\/p>\n<h3 id=\"h-la-historia-real-detras-de-la-nbsp-pelicula-nbsp\" class=\"wp-block-heading\">La historia real detr\u00e1s de la pel\u00edcula<\/h3>\n<p>La cinta est\u00e1 basada directamente en los hechos que rodearon al asesino en\u00a0<a href=\"https:\/\/dps.alaska.gov\/AST\/PIO\/PressReleases\/Victim-of-Serial-Killer-Robert-Hansen-Identified-3\">serie Robert Hansen<\/a>, que entre 1972 y 1983, mat\u00f3, secuestro y viol\u00f3 a diecisiete mujeres. Todas, en el \u00e1rea rural de Anchorage (Alaska). Uno de los datos m\u00e1s escalofriantes sobre Hansen, es que se comprob\u00f3 que en varias ocasiones oblig\u00f3 a sus v\u00edctimas a huir a trav\u00e9s de campos nevados. Eso, para luego, darles caza con una escopeta\u00a0<a href=\"https:\/\/ruger.com\/products\/mini14\/overview.html\">Ruger Mini-14<\/a>\u00a0<strong>y cuchillos para despellejar cuero animal.\u00a0<\/strong><\/p>\n<p>De la misma manera que la pel\u00edcula, el asesino evitaba ser atrapado, cortando los dedos y huellas dactilares de sus v\u00edctimas, as\u00ed como cortando su cabello o desfigur\u00e1ndolas. Finalmente, Hansen fue capturado en 1983 y condenado a 461 a\u00f1os de prisi\u00f3n. En 2014 muri\u00f3 por causas naturales. \u00bfUn dato curioso? El personaje de Nicolas Cage, est\u00e1 basado\u00a0<strong>en el agente\u00a0<a href=\"https:\/\/www.noiser.com\/detectives-dont-sleep\/hunting-the-hunter-part-2-of-2\">Glenn Flothe<\/a>, l\u00edder del grupo de investigadores que permiti\u00f3 encontrar al asesino.\u00a0<\/strong><\/p>\n<h2 id=\"h-el-estrangulador-de-boston-disney-nbsp\" class=\"wp-block-heading has-text-align-center\">El estrangulador de Boston (Disney+)<\/h2>\n<p>En 2023, Matt Ruskin dirigi\u00f3 esta\u00a0<a href=\"https:\/\/hipertextual.com\/2023\/03\/el-estrangulador-de-boston-critica-disney\">cinta<\/a>, que relata el clima de p\u00e1nico y paranoia, que provocaron los asesinatos del llamado Estrangulador de Boston. Pero en lugar de que el guion\u200a\u2014\u200aque tambi\u00e9n escribe el director\u200a\u2014\u200ase enfocara en la actuaci\u00f3n de un funcionario policial o el mismo asesino, lo hace en la figura de la periodista\u00a0<a href=\"https:\/\/www.theguardian.com\/film\/2023\/mar\/20\/boston-strangler-film-keira-knightley-journalists\">Loretta McLaughlin<\/a>. Interpretada por Keira Knightley, el personaje es el hilo conductor que permite\u00a0<strong>comprender c\u00f3mo impactaron durante la d\u00e9cada de 1960, los cr\u00edmenes de un hombre brutal.\u00a0<\/strong><\/p>\n<p>Al mismo tiempo, la pel\u00edcula permite entender c\u00f3mo tanto los investigadores como los periodistas, debieron unir fuerzas para detener al criminal. Algo que llev\u00f3 a una colaboraci\u00f3n inc\u00f3moda e in\u00e9dita entre ambos gremios. Gracias a lo cual, finalmente Albert DeSalvo (David Dastmalchian), fue atrapado y enjuiciado por los cr\u00edmenes en Boston. No obstante, la pel\u00edcula deja entrever que, a pesar de la captura,\u00a0<strong>quedaron muchos cabos sueltos y puntos en blanco en la investigaci\u00f3n.\u00a0<\/strong><\/p>\n<h3 id=\"h-la-historia-real-detras-de-la-nbsp-pelicula-nbsp-0\" class=\"wp-block-heading\">La historia real detr\u00e1s de la pel\u00edcula<\/h3>\n<p>La pel\u00edcula logra explorar en buena parte de lo acontecido durante la oleada de terror que ocasionaron los cr\u00edmenes del Estrangulador de Boston. El criminal, al que se le atribuyen 13 asesinatos, aterroriz\u00f3 al \u00e1rea metropolitana de la ciudad durante 1960 y 1965. Casi una d\u00e9cada antes, que se implementaran los m\u00e9todos de b\u00fasqueda e investigaci\u00f3n<strong>\u00a0dedicados directamente a los asesinos en serie.\u00a0<\/strong><\/p>\n<p>Un giro de los acontecimientos, que provoc\u00f3 que no se llevara registro de las similitudes en las diferentes escenas de los cr\u00edmenes o se compararan datos biol\u00f3gicos. Finalmente, se acus\u00f3 a\u00a0<a href=\"https:\/\/hipertextual.com\/2023\/03\/historia-real-el-estrangulador-de-boston-disney\">Albert DeSalvo<\/a>\u00a0de las muertes, bas\u00e1ndose en su confesi\u00f3n y<strong>\u00a0al haber aportado datos que solo pod\u00eda conocer el criminal.<\/strong><\/p>\n<p>A pesar de eso, tal y como cuenta la pel\u00edcula, a\u00fan en la actualidad hay dudas consistentes acerca de que en realidad sea el asesino. Por lo que se cree que, aunque cometi\u00f3 varios de los asesinatos, es probable que otros casos atribuidos al estrangulador, sean autor\u00eda de varias personas distintas.\u00a0Y si te lo preguntas, s\u00ed, la periodista\u00a0<a href=\"https:\/\/screenrant.com\/boston-strangler-jean-loretta-what-happened-after\/\">Loretta McLaughlin fue una pieza clave<\/a>\u00a0en la investigaci\u00f3n.<\/p>\n<h2 id=\"h-ted-bundy-en-la-mente-del-asesino-prime-video\" class=\"wp-block-heading has-text-align-center\">Ted Bundy. En la mente del asesino (Prime\u00a0Video)<\/h2>\n<p>La cineasta Amber Sealey mostr\u00f3 en esta pel\u00edcula de 2021, la oscuridad de la mente de un criminal confeso y que adem\u00e1s, jam\u00e1s muestra el m\u00e1s m\u00ednimo arrepentimiento. Ted (interpretado por Luke Kirby), desea contar su historia. Pero hacerlo bajo sus t\u00e9rminos y desde la experiencia de haber burlado por casi una<strong>\u00a0d\u00e9cada a todos los funcionarios que intentaron atraparlo.\u00a0<\/strong><\/p>\n<p>Por lo que cuando el periodista Bill Hagmaier (<a href=\"https:\/\/hipertextual.com\/2024\/05\/viggo-mortensen-aragorn-el-senor-de-los-anillos-gollum\">Elijah Wood<\/a>), desee entrevistarlo, aceptar\u00e1 sin reparos. En particular porque Ted, condenado a muerte, intentar\u00e1 dejar su retorcida huella en el mundo de una manera u otra. Un giro que permitir\u00e1 a Bill indagar en profundidad en la psiquis del asesino y<strong>\u00a0su retorcida perspectiva acerca de la violencia que desencaden\u00f3.\u00a0<\/strong><\/p>\n<h3 id=\"h-historia-real-detras-de-la-nbsp-pelicula\" class=\"wp-block-heading\">Historia real detr\u00e1s de la pel\u00edcula<\/h3>\n<p><a href=\"https:\/\/www.inesem.com.ve\/articulos-investigacion\/Ted-Bundy\">Ted Bundy<\/a>\u00a0secuestr\u00f3, viol\u00f3 y asesin\u00f3 a 36 mujeres y ni\u00f1as, durante la d\u00e9cada de 1970. Al menos, ese fue el n\u00famero que pudo probarse durante el juicio en su contra, el m\u00e1s medi\u00e1tico en su estilo que se recuerde. Tambi\u00e9n,\u00a0<a href=\"https:\/\/psychology.as.uky.edu\/psychology-researcher-unravels-serial-killer-ted-bundys-mental-health\">el que populariz\u00f3 el t\u00e9rmino asesino en serie<\/a>\u00a0entre la prensa. Durante su \u00e9poca en activo, fing\u00eda tener una fractura o una discapacidad motora, por lo que ped\u00eda ayuda a sus v\u00edctimas.<strong>\u00a0Eso, para luego terminar secuestr\u00e1ndolas.\u00a0<\/strong><\/p>\n<p>De la misma manera que en la pel\u00edcula, Bundy sostuvo entrevistas con diversos periodistas. En especial, una vez que confes\u00f3 algunos de sus cr\u00edmenes, unos diez a\u00f1os despu\u00e9s de ser capturado. Por lo que, aunque el argumento de\u00a0<em>Ted Bundy. En la mente del asesino<\/em>\u00a0<strong>no es real, es la s\u00edntesis de experiencias parecidas con el criminal.\u00a0<\/strong><\/p>\n<aside class=\"scaip scaip-3    \"><\/aside>\n<h2 id=\"h-asesinato-por-decreto-nbsp-filmin-nbsp\" class=\"wp-block-heading has-text-align-center\">Asesinato por decreto (Filmin)<\/h2>\n<p>Para la ocasi\u00f3n, el director Bob Clark convirti\u00f3 a la historia de un asesino c\u00e9lebre en un duelo de inteligencia y recursos. Eso, al imaginar al detective m\u00e1s famoso de la ficci\u00f3n, Sherlock Holmes (Christopher Plummer), mientras investiga una serie de asesinatos en Whitechapel. Un punto de vista que permite al guion de John Hopkins reflexionar sobre los errores que la polic\u00eda de finales del siglo\u00a0<strong>XIX cometi\u00f3 durante investigaciones parecidas.\u00a0<\/strong><\/p>\n<p>Lo m\u00e1s interesante de esta pel\u00edcula de 1979 es que, a pesar de su tema escabroso, logra ser una revisi\u00f3n maliciosa y sat\u00edrica acerca de Holmes. Tambi\u00e9n, una perspectiva fresca acerca de la investigaci\u00f3n, permitiendo\u00a0<strong>al c\u00e9lebre detective usar sus t\u00e1cticas y descubrimientos cient\u00edficos para encontrar al asesino.\u00a0<\/strong><\/p>\n<h3 id=\"h-historia-real-detras-de-la-nbsp-pelicula-nbsp\" class=\"wp-block-heading\">Historia real detr\u00e1s de la pel\u00edcula<\/h3>\n<p>Por supuesto, la cinta est\u00e1 basada de manera muy libre, en los cr\u00edmenes del llamado<a href=\"https:\/\/hipertextual.com\/2019\/05\/posible-tumba-hombre-elefante-gracias-jack-destripador\">\u00a0Jack el Destripador<\/a>. Un asesino que mat\u00f3 a cinco mujeres en el barrio londinense de Whitechapel en 1888. Y aunque la producci\u00f3n no lo muestra, los asesinatos provocaron una ola de terror en la ciudad que a la distancia, resulta inquietante. En especial, debido a que el homicida extirpaba los \u00f3rganos y desfiguraba los rostros<strong>\u00a0de las v\u00edctimas con una precisi\u00f3n quir\u00fargica.<\/strong><\/p>\n<p>Scotland Yard investig\u00f3 a m\u00e1s de 300 sospechosos, sin lograr encontrar al criminal. \u00bfUn dato curioso? Recientemente, se conoci\u00f3 la noticia de que la identidad del asesino hab\u00eda sido descubierta,\u00a0<a href=\"https:\/\/www.science.org\/content\/article\/does-new-genetic-analysis-finally-reveal-identity-jack-ripper\" target=\"_blank\" rel=\"noreferrer noopener\">gracias a una prueba de ADN<\/a>. El procedimiento permiti\u00f3 comparar la sangre de un descendiente del principal sospechoso de la \u00e9poca con una muestra encontrada en una bufanda junto al cuerpo de una v\u00edctima. El resultado demostr\u00f3\u200a\u2014\u200ao intent\u00f3 demostrar\u200a\u2014\u200a<strong>que el asesino era Aaron Kosminski, un barbero polaco de Londres.\u00a0<\/strong><\/p>\n<h2 id=\"h-cronica-de-un-asesino-en-serie-prime-nbsp-video-nbsp\" class=\"wp-block-heading has-text-align-center\">Cr\u00f3nica de un asesino en serie (Prime Video)<\/h2>\n<p>Incluso,<a href=\"https:\/\/hipertextual.com\/2024\/07\/las-5-mejores-peliculas-del-director-de-parasite\">\u00a0Bong Jong-ho<\/a>, director de\u00a0<em><a href=\"https:\/\/hipertextual.com\/2025\/03\/mickey-17-critica-salvaje-critica-al-capitalismo-de-robert-pattinson-y-el-director-de-parasitos\">Mickey 17<\/a><\/em>, hizo una incursi\u00f3n en el\u00a0<em>neo noir<\/em>\u00a0con esta curiosa pel\u00edcula que explora en la vida de un asesino en serie surcoreano. Lo complicado de la situaci\u00f3n, es que la pel\u00edcula narra la incapacidad de la polic\u00eda para manejar una cadena de hechos violentos, in\u00e9ditos en el pa\u00eds. Algo que llevar\u00e1 a\u00a0<strong>dos investigadores a unir fuerzas y recursos para descubrir la identidad del criminal.\u00a0<\/strong><\/p>\n<aside class=\"scaip scaip-4    \"><\/aside>\n<p>Como no pod\u00eda ser de otra forma, el director no perdi\u00f3 la oportunidad de utilizar la historia, para explorar en el clasismo y la desigualdad. Todo, en medio de un humor negr\u00edsimo<strong>\u00a0que se mezcla con escenas escalofriantes. Un deleite para los fan\u00e1ticos del g\u00e9nero.<\/strong><\/p>\n<h3 id=\"h-historia-real-detras-de-la-nbsp-pelicula-nbsp-0\" class=\"wp-block-heading\">Historia real detr\u00e1s de la pel\u00edcula<\/h3>\n<p>Lee Choon-jae o el asesino de Hwaseong, fue un criminal real que tiene el extra\u00f1o honor de haber sido el primer asesino en serie de Corea del Sur. Entre 1986 y 1994, el homicida secuestr\u00f3 y mat\u00f3 a quince mujeres y ni\u00f1as. Tambi\u00e9n, cometi\u00f3 docenas de agresiones sexuales, una circunstancia que brind\u00f3 a la polic\u00eda del pa\u00eds, el rastro biol\u00f3gico del criminal.\u00a0<strong>Algo que a la larga permitir\u00eda su captura.\u00a0<\/strong><\/p>\n<p><a class=\"url fn n\" href=\"https:\/\/hipertextual.com\/autor\/aglaiaberlutti\">Aglaia Berlutti<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando\u00a0El silencio de los corderos\u00a0se estren\u00f3 en 1991, caus\u00f3 revuelo. No solo porque\u00a0Jonathan Demme\u00a0logr\u00f3 captar el aire siniestro y violento del\u00a0libro\u00a0de Thomas Harris que adapta. Tambi\u00e9n, porque la forma en que explor\u00f3 en las muertes perpetradas por el criminal ficticio Buffalo Bill (Ted Levine) revolucion\u00f3 el g\u00e9nero de pel\u00edculas basadas en asesinos en serie. El&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":2142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[7],"tags":[],"class_list":["post-2160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-peliculas"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[1],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"_links":{"self":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts\/2160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/comments?post=2160"}],"version-history":[{"count":1,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts\/2160\/revisions"}],"predecessor-version":[{"id":2161,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts\/2160\/revisions\/2161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/media\/2142"}],"wp:attachment":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/media?parent=2160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/categories?post=2160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/tags?post=2160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}