{"id":2394,"date":"2025-05-31T20:40:38","date_gmt":"2025-05-31T18:40:38","guid":{"rendered":"https:\/\/bitacoraenlared.es\/chicas\/?p=2394"},"modified":"2025-05-28T20:42:34","modified_gmt":"2025-05-28T18:42:34","slug":"un-joven-hackea-linkedin-para-conseguir-trabajo-con-este-sencillo-truco-ha-recibido-ofertas-en-meta-y-microsoft","status":"publish","type":"post","link":"https:\/\/bitacoraenlared.es\/chicas\/un-joven-hackea-linkedin-para-conseguir-trabajo-con-este-sencillo-truco-ha-recibido-ofertas-en-meta-y-microsoft\/","title":{"rendered":"Un joven hackea LinkedIn para conseguir trabajo: con este sencillo truco ha recibido ofertas en Meta y Microsoft"},"content":{"rendered":"<p>Ser una de las primeras personas que\u00a0<a title=\"Los mejores meses del a\u00f1o para tener una b\u00fasqueda de trabajo exitosa en Espa\u00f1a, seg\u00fan los expertos\" href=\"https:\/\/www.businessinsider.es\/desarrollo-profesional\/mejores-meses-ano-tener-exito-buscando-trabajo-919955\">solicitan un empleo puede aumentar tus posibilidades de \u00e9xito<\/a>\u00a0en la b\u00fasqueda de trabajo. Un truco de LinkedIn ha ayudado a un miembro de la generaci\u00f3n Z inmerso en el sector de la tecnolog\u00eda a superar la avalancha de otros solicitantes.<\/p>\n<p>En 2018, cuando Michael Yan estudiaba primer a\u00f1o de inform\u00e1tica en la Universidad de Stanford (Estados Unidos), quer\u00eda\u00a0<a title=\"Si est\u00e1s buscando pr\u00e1cticas en empresas estos 4 trucos sencillos te ayudar\u00e1n a resaltar sobre el resto de candidatos\" href=\"https:\/\/www.businessinsider.es\/desarrollo-profesional\/4-trucos-sencillos-conseguir-practicas-empresas-732209\">tener una ventaja competitiva a la hora de solicitar pr\u00e1cticas<\/a>. Despu\u00e9s de buscar su trabajo deseado y utilizar\u00a0<strong>la funci\u00f3n de LinkedIn<\/strong>\u00a0que ordena\u00a0<a title=\"Las nuevas reglas de la b\u00fasqueda de empleo: la gu\u00eda definitiva para encontrar trabajo en 2025\" href=\"https:\/\/www.businessinsider.es\/desarrollo-profesional\/nuevas-reglas-busqueda-empleo-guia-definitiva-encontrar-trabajo-2025-1433267\">los roles publicados en el \u00faltimo d\u00eda<\/a>,\u00a0<strong>cambi\u00f3 los n\u00fameros al final de la URL<\/strong>\u00a0del sitio web de 86400 (el n\u00famero de segundos que hay en 24 horas) a 3600 (la cantidad de segundos en una hora).<\/p>\n<p><strong>\u00abHa sido muy \u00fatil para preseleccionar los empleos publicados recientemente a los que pod\u00eda dar prioridad\u00bb<\/strong>, explica Yan, de 25 a\u00f1os, a\u00a0<em>Business Insider<\/em>.<\/p>\n<p>Yan comparte que\u00a0<strong>este truco le ha ayudado a centrarse en las ofertas de empleo m\u00e1s recientes<\/strong>, y cree que es una de las razones por las que consigui\u00f3 pr\u00e1cticas despu\u00e9s de sus dos primeros a\u00f1os en la universidad. Durante su segundo a\u00f1o, en 2019, le ofrecieron pr\u00e1cticas en Microsoft y Meta, y acept\u00f3 esta \u00faltima.<\/p>\n<p>En 2020, Yan abandon\u00f3 Stanford para fundar Simplify, que ofrece un copiloto de IA cuyo objetivo es ayudar a las personas a encontrar y solicitar empleo. Afirma que presentar la solicitud pronto sigue siendo uno de sus principales consejos para quienes buscan trabajo.<\/p>\n<p><a title=\"'Business Insider' habla con m\u00e1s de 750 personas que han afrontado dificultades para encontrar trabajo: esto ha sido lo m\u00e1s complicado\" href=\"https:\/\/www.businessinsider.es\/desarrollo-profesional\/business-insider-habla-750-personas-han-afrontado-dificultades-encontrar-trabajo-ha-sido-complicado-1417072\" target=\"_blank\" rel=\"noopener\">Cientos de estadounidenses han declarado a\u00a0<em>Business Insider<\/em><\/a>\u00a0que han tenido\u00a0<a title=\"Espa\u00f1a, entre los pa\u00edses europeos donde es m\u00e1s dif\u00edcil encontrar trabajo para los reci\u00e9n graduados\" href=\"https:\/\/www.businessinsider.es\/desarrollo-profesional\/espana-paises-europeos-donde-dificil-encontrar-trabajo-recien-graduados-1403310\">problemas para encontrar empleo<\/a>\u00a0en el \u00faltimo a\u00f1o. Si bien la tasa de desempleo sigue siendo baja en comparaci\u00f3n con los niveles hist\u00f3ricos, las empresas est\u00e1n contratando a casi la tasa m\u00e1s baja desde 2013, excluyendo una ca\u00edda temporal en 2020. En respuesta a estos desaf\u00edos, algunos estadounidenses est\u00e1n buscando formas de destacar. Expertos en carreras profesionales de LinkedIn, Indeed y ZipRecruiter apuntan a\u00a0<em>Business Insider<\/em>\u00a0que\u00a0<strong>postularse a empleos con anticipaci\u00f3n podr\u00eda dar a los candidatos una ventaja<\/strong>\u00a0en el desafiante\u00a0<a title=\"La Semana Santa impulsa el mercado laboral hasta un nuevo r\u00e9cord de empleo, con 230.993 afiliados m\u00e1s y 67.420 parados menos en abril\" href=\"https:\/\/www.businessinsider.es\/economia\/semana-santa-impulsa-mercado-laboral-empleo-paro-abril-1459140\">mercado laboral actual<\/a>.<\/p>\n<p>Cuando se le pregunta sobre el truco del filtro de trabajo de Yan, LinkedIn responde a\u00a0<em>BI<\/em>\u00a0que las restricciones de palabras clave y filtros de b\u00fasqueda frustran a algunos buscadores de empleo, pero que la compa\u00f1\u00eda est\u00e1 trabajando para reducir esas limitaciones.<\/p>\n<h2>Presentar la solicitud antes de tiempo podr\u00eda \u00abcambiar tus probabilidades\u00bb<\/h2>\n<p>Estar entre los primeros solicitantes tiene varias ventajas.<\/p>\n<p>Andrew McCaskill, experto en carreras profesionales de LinkedIn, sugiere a los solicitantes de empleo que configuren alertas para determinados tipos de puestos, de modo que puedan presentar su candidatura r\u00e1pidamente tras la publicaci\u00f3n de la oferta. A\u00f1ade que\u00a0<strong>solicitar un empleo en LinkedIn en los primeros 10 minutos<\/strong>\u00a0de recibir una alerta puede multiplicar hasta por cuatro las posibilidades de recibir una respuesta de la empresa.<\/p>\n<div data-mrf-position=\"entreparrafos1\"><\/div>\n<p>\u00abSer de los primeros en presentar una solicitud, sobre todo si se trata de un trabajo que realmente se desea o para el que se est\u00e1 muy cualificado, deber\u00eda formar parte de la estrategia de b\u00fasqueda de empleo\u00bb, afirma.<\/p>\n<p>Sam DeMase, experta en carreras profesionales de ZipRecruiter, se muestra de acuerdo y complementa que algunas empresas cierran las ofertas de empleo despu\u00e9s de recibir un determinado n\u00famero de solicitudes, lo que puede ocurrir r\u00e1pidamente. En la medida de lo posible,\u00a0<strong>recomienda presentar la solicitud en los tres d\u00edas siguientes<\/strong>\u00a0a la publicaci\u00f3n del puesto.<\/p>\n<p>\u00abLos empleadores tienen m\u00e1s probabilidades de entrevistar, hacer una oferta y contratar a los solicitantes m\u00e1s tempranos, por lo que moverse r\u00e1pido puede cambiar literalmente sus probabilidades\u00bb, asegura.<\/p>\n<p>DeMase afirma que presentar la solicitud con antelaci\u00f3n puede ser especialmente importante para los puestos de nivel inicial, en los que suele haber un gran n\u00famero de candidatos. Adem\u00e1s, considera que los puestos en empresas de nueva creaci\u00f3n y en los sectores minorista y de atenci\u00f3n al cliente tienden a cubrirse con bastante rapidez.<\/p>\n<p>Jennifer Herrity, experta en tendencias profesionales de Indeed, afirma que\u00a0<strong>una solicitud temprana puede demostrar entusiasmo<\/strong>\u00a0<strong>y rapidez<\/strong>, y que lo mejor es presentarse a un puesto como m\u00e1ximo una semana o dos despu\u00e9s de que se haya publicado.<\/p>\n<p>Sin duda, el momento de presentar la solicitud es solo uno de los factores en la b\u00fasqueda de empleo. Los expertos profesionales con los que ha hablado\u00a0<em>Business Insider<\/em>\u00a0se\u00f1alan que\u00a0<strong>los solicitantes de empleo no deben sacrificar la calidad de la solicitud solo por llegar pronto<\/strong>. Tambi\u00e9n creen que deben adaptar sus curr\u00edculos a cada puesto y asegurarse de que los puestos a los que optan se ajustan a sus habilidades y experiencia.<\/p>\n<p>\u00abM\u00e1s importante que presentar la solicitud con rapidez \u2014ya sea en 24 horas o en una hora\u2014 es encajar bien en el puesto al que optas y que tu solicitud te muestre de la mejor manera posible\u00bb, concluye McCaskill.<\/p>\n<p><a class=\"author-block_text__A5F3o\" href=\"https:\/\/www.businessinsider.es\/redaccion\/carlos-galan-feced\" rel=\"author\">Carlos Gal\u00e1n Feced<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ser una de las primeras personas que\u00a0solicitan un empleo puede aumentar tus posibilidades de \u00e9xito\u00a0en la b\u00fasqueda de trabajo. Un truco de LinkedIn ha ayudado a un miembro de la generaci\u00f3n Z inmerso en el sector de la tecnolog\u00eda a superar la avalancha de otros solicitantes. En 2018, cuando Michael Yan estudiaba primer a\u00f1o de&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":2375,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-2394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[1],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"_links":{"self":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts\/2394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/comments?post=2394"}],"version-history":[{"count":1,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts\/2394\/revisions"}],"predecessor-version":[{"id":2395,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts\/2394\/revisions\/2395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/media\/2375"}],"wp:attachment":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/media?parent=2394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/categories?post=2394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/tags?post=2394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}