{"id":2440,"date":"2025-06-10T09:11:21","date_gmt":"2025-06-10T07:11:21","guid":{"rendered":"https:\/\/bitacoraenlared.es\/chicas\/?p=2440"},"modified":"2025-06-08T09:15:33","modified_gmt":"2025-06-08T07:15:33","slug":"las-ensenanzas-sobre-el-sexo-del-poeta-obsceno-de-la-antigua-roma","status":"publish","type":"post","link":"https:\/\/bitacoraenlared.es\/chicas\/las-ensenanzas-sobre-el-sexo-del-poeta-obsceno-de-la-antigua-roma\/","title":{"rendered":"Las ense\u00f1anzas sobre el sexo del poeta obsceno de la antigua Roma"},"content":{"rendered":"<p>Nacido en Verona alrededor del a\u00f1o 87 a.C., no hay otro bardo de la Antig\u00fcedad como\u00a0<b>Cayo Valerio Catulo<\/b>, nacido en buena cuna, exitoso poeta y cuya obra estuvo\u00a0<b>marcada por el amor y el\u00a0<a href=\"https:\/\/www.elconfidencial.com\/tags\/temas\/sexo-5290\/\" target=\"_self\">sexo<\/a>\u00a0a tutipl\u00e9n<\/b>. Su principal objetivo amoroso \u2013pero no el \u00fanico\u2013 era\u00a0<b>Clodia<\/b>, casada con el maduro gobernador de la galia\u00a0<b>Quinto Cecilo Metelo C\u00e9ler<\/b>, y a la que llamaba\u00a0<b>Lesbia<\/b>\u00a0en homenaje a\u00a0<b>Safo de Lesbos<\/b>. El joven, que acababa de llegar a Roma desde su hogar natal de Verona, se qued\u00f3 encandilado por la belleza y atractivo de la esposa. Fue todo un trauma: su amada le fue infiel a la primera de cambio, y de ah\u00ed deriv\u00f3 la mayor parte de la l\u00edrica del autor.<\/p>\n<p>En su poes\u00eda se repiten las referencias a los genitales, los fluidos y la sodom\u00eda. En el que seguramente sea\u00a0<b>el poema<\/b><b>\u00a0m\u00e1s expl\u00edcito de la era cl\u00e1sica<\/b>, Catulo se deja llevar hasta el punto de que, como recuerda un art\u00edculo publicado en &#8216;<a href=\"http:\/\/io9.gizmodo.com\/a-latin-poem-so-filthy-it-wasnt-translated-until-the-2-1589504370\" target=\"_blank\" rel=\"nofollow noopener\">Gizmodo<\/a>&#8216;, su obra no fue traducida al ingl\u00e9s hasta el siglo XX. No solo por su obscenidad, sino tambi\u00e9n por su vilurencia, que veces le lleva a amenazar con una violaci\u00f3n sodomita.<\/p>\n<p>Es el caso de su poema n\u00famero XVI, conocido como\u00a0<b>&#8216;Pedicabo ego vos et irrumabo&#8217;<\/b>, que podr\u00eda traducirse como (atenci\u00f3n, contenido expl\u00edcito) \u201cEn tu culo y en tu boca\u201d. Est\u00e1 dedicado, como otros de su producci\u00f3n, a\u00a0<b>Marco Furio Bibaculo\u00a0<\/b>(que hab\u00eda tenido un l\u00edo con otro amante de Catulo llamado\u00a0<b>Juvencio<\/b>) y\u00a0<b>Marco Aurelio Cota Maximo Mesalino<\/b>. En este texto, directamente amenaza con sodomizar y humillar a sus enemigos amorosos en una letra que ni una canci\u00f3n de\u00a0<b>Nine Inch Nails<\/b>: \u201cFuck you, up your ass and in your mouth\u201d fue la traducci\u00f3n que realiz\u00f3\u00a0<b>Carl Sesar<\/b>\u00a0en 1974.<\/p>\n<p>&nbsp;<\/p>\n<p>Cuidado con utilizarlo a la ligera. Como recogieron los\u00a0<a href=\"https:\/\/www.theguardian.com\/culture\/charlottehigginsblog\/2009\/nov\/24\/catullus-mark-lowe\" target=\"_blank\" rel=\"nofollow noopener\">medios brit\u00e1nicos<\/a>, en 2009,\u00a0<b>Mark Lowe<\/b>\u00a0de Nomos Capital fue demandado por una trabajadora a la que le envi\u00f3 el primer verso del poema por correo electr\u00f3nico. S\u00ed, ese que hace referencia a lo anal y oral. \u00bfSu defensa? Que era algo\u00a0<b>\u201cburlesco\u201d<\/b>, pura diversi\u00f3n tanto en el siglo I d.C. como en el XXI.<\/p>\n<p>Muy poco constructivo, pero \u00bfpodemos aprender algo positivo de su obra? Vamos a sumergirnos en algunos de los 25 poemas dedicados a su amada Lesbia (de los 116 que le han sobrevivido), sobre todo aquellos en los que Catulo a\u00fan no se hab\u00eda dejado llevar por la furia ante su antigua amante al darse cuenta de que lo suyo no hab\u00eda significado nada para ella y que, de hecho, era su \u00faltima opci\u00f3n incluso despu\u00e9s de quedarse\u00a0<a href=\"https:\/\/www.elconfidencial.com\/alma-corazon-vida\/2016-04-20\/hay-un-monton-de-ricos-buscando-esposa-y-esta-mujer-se-las-consigue_1186410\/\" target=\"_self\">viuda<\/a>. O quiz\u00e1 sea una buena ense\u00f1anza:\u00a0<b>si te rechazan, no te comportes como un cr\u00edo herido.<\/b><\/p>\n<h2 class=\"bodyTitle\">Entre las s\u00e1banas del placer<\/h2>\n<p>\u201cVivamos, Lesbia m\u00eda, y amemos: los rumores severos de los viejos que no valgan ni un duro todos juntos\u201d. Este es el arranque del poema 5 de Catulo, probablemente el m\u00e1s candoroso de todos los destinados a su objeto amoroso, y en el que apuesta por\u00a0<b>experimentar el amor sin someterse al juicio de los dem\u00e1s<\/b>. \u201cSe pone y sale el sol, mas a nosotros, apenas se nos pone la luz breve, sola noche sin dormir nos toca\u201d.<\/p>\n<p>Parece ser que el bueno de Catulo era de los que amaban\u00a0<b>las\u00a0<\/b><b>largas sesiones de exploraci\u00f3n sexual<\/b>: \u201cPero dame mil\u00a0<a href=\"https:\/\/blogs.elconfidencial.com\/alma-corazon-vida\/divan-digital\/2013-04-29\/los-enormes-beneficios-de-un-buen-beso-ademas-del-placer_204405\/\" target=\"_self\">besos<\/a>, luego ciento, despu\u00e9s mil otra vez, de nuevo ciento, luego otros mil a\u00fan, y luego ciento&#8230;\u201d \u00bfM\u00e1s vale cantidad que calidad? En el poema n\u00famero siete, Catulo escribe: \u201cPreguntas cu\u00e1ntos a m\u00ed besares tuyos, Lesbia, sean bastante y de sobra\u201d. La respuesta es \u201ctantos besos muchos que t\u00fa beses, para el vesano Catulo bastante y de sobra es\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Algo debi\u00f3 ocurrir entre el poema 7 y el 8, puesto que en este \u00faltimo empieza a manifestarse el desencanto amoroso que explotar\u00eda a partir del n\u00famero 60, con sus altibajos. Frente a un panorama idealizado (\u201cCuando aquellas muchas cosas divertidas se hac\u00edan, que t\u00fa quer\u00edas [Catulo], y\u00a0<b>tu chica de querer no dejaba<\/b>, fulgieron verdaderamente c\u00e1ndidos para ti los soles\u201d), parece ser que el poeta fue rechazado por primera vez. \u201cSalud, ni\u00f1a, ya Catulo resiste, y no te requerir\u00e1 ni rogar\u00e1\u201d. Se le debi\u00f3 pasar r\u00e1pido el resquemor, porque pronto aparecen\u00a0<b>Veranio<\/b>\u00a0(\u201cpleg\u00e1ndome a tu cuello agradable, tu boca y ojos suavemente besar\u00e9\u201d) y el\u00a0<b>Varo<\/b>.<\/p>\n<p>&nbsp;<\/p>\n<p>De entre todos los poemas picantones, seguramente no hay ninguno m\u00e1s atrevido que el 32, dedicado a la dulce\u00a0<b>Ipsitila<\/b>, a el que el poeta\u00a0<b>ofrece sus servicios sexuales antes de servirse \u00e9l mismo<\/b>. \u201cSi algo has de hacer, al punto m\u00e1ndalo, pues bien comido yazgo, y harto, boca arriba, atravieso t\u00fanica y palio\u201d. En otras palabras, no hay que ser muy listo para imaginarnos entre Catulo e Ipsitila la postura sexual de la &#8216;<a href=\"https:\/\/www.elconfidencial.com\/alma-corazon-vida\/2015-05-28\/cuidado-con-lo-que-haces-las-cinco-posiciones-sexuales-mas-peligrosas_855183\/\" target=\"_self\">cowgirl<\/a>&#8216; (\u00bfquiz\u00e1 invertida?). En algo parece que han cambiado las cosas: parece ser que tener el est\u00f3mago lleno es lo mejor si lo que queremos es arrasar entre las s\u00e1banas.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00bfQu\u00e9 habr\u00eda hecho Catulo en mi lugar?<\/p>\n<p>&nbsp;<\/p>\n<p>Tan conocida es la fama de s\u00e1tiro del poeta que incluso algunas p\u00e1ginas se han servido de su figura para abrir\u00a0<b>un consultorio sentimental de tono humor\u00edstico<\/b>. Es el caso de &#8216;<a href=\"https:\/\/thehairpin.com\/sex-tips-from-catullus-7a712620bf27#.8a8mn9of3\" target=\"_blank\" rel=\"nofollow noopener\">The Hairpin<\/a>&#8216; y sus \u201cConsejos sexuales de Catulo\u201d, en el que un sex\u00f3logo (o sex\u00f3loga) bajo seud\u00f3nimo responde a todas las dudas que los heridos amantes puedan tener. Por ejemplo, a una mujer que lleva cinco a\u00f1os con su pareja, le recomienda \u201cno llevar nada m\u00e1s que una hoja de laurel, cubrirte en miel y comprarte una nueva toga\u201d.<\/p>\n<p>No es que el poeta verdadero fuese precisamente un dechado de virtudes. Incluso en los poemas clasificados como rom\u00e1nticos hay acusaciones bien macarras: \u201c\u00bfAcaso porque contiguos os sent\u00e1is, cien o doscientos insulsos, no cre\u00e9is que me atrever\u00e9 yo que al par los doscientos asistentes me la (\u00a1pip! que el lector imagine lo que quiera)?\u201d Son los\u00a0<a href=\"https:\/\/www.elconfidencial.com\/alma-corazon-vida\/2015-01-11\/los-celos-otra-de-las-cosas-que-nos-hacen-muy-diferentes-a-hombres-y-mujeres_618118\/\" target=\"_self\">celos<\/a>\u00a0los que vuelven a conducir su conducta: \u201cA ella, buenos y dichosos, todos la am\u00e1is\u201d. En el poema aparece tambi\u00e9n una curiosa pregunta ret\u00f3rica: \u201c\u00bfSolo pens\u00e1is que ten\u00e9is pollas vosotros, que a solos vosotros l\u00edcito es cuanto hay de chicas follaros y creernos a los dem\u00e1s machos cabr\u00edos?\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>Qued\u00e9monos, mejor, con alguno de los ocasionales ataques de romanticismo que Catulo sufr\u00eda de vez en cuando, probablemente para ampliar su ya de por s\u00ed amplia (y muy variada) cuenta de amantes. Quiz\u00e1 el 109: \u201cMi vida, me propones que el amor este nuestro perpetuo ser\u00e1\u201d. O el 87\u201d:\u00a0<b>Ninguna mujer puede decirse tan amada<\/b>\u00a0en verdad como por m\u00ed la Lesbia amada es\u201d.<\/p>\n<p>Una \u00faltima lecci\u00f3n. Los poemas de Catulo presentan a Clodia como una mujer f\u00e1cil (le acusa de haber tenido 300\u00a0<a href=\"https:\/\/www.elconfidencial.com\/alma-corazon-vida\/2016-09-02\/amantes-tienen-la-esperanza-de-que-el-hombre-casado-deje-a-su-mujer_1253747\/\" target=\"_self\">amantes<\/a>), traicionera y cruel. Sin embargo, los principales testimonios que se conservan provienen de hombres despechados o vengativos, como tambi\u00e9n ocurri\u00f3 en el caso de\u00a0<b>Cicer\u00f3n<\/b>, enemigo a muerte de su hermano Clodio, y que la utiliz\u00f3 como\u00a0<b>arma arrojadiza en sus c\u00e9lebres discursos<\/b>. Una buena muestra de que la historia la escriben los vencedores\u2026 que suelen ser hombres.<\/p>\n<p><a class=\"authorSignature__link\" href=\"https:\/\/www.elconfidencial.com\/autores\/hector-g-barnes-120\/\">H\u00e9ctor G. Barn\u00e9s<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nacido en Verona alrededor del a\u00f1o 87 a.C., no hay otro bardo de la Antig\u00fcedad como\u00a0Cayo Valerio Catulo, nacido en buena cuna, exitoso poeta y cuya obra estuvo\u00a0marcada por el amor y el\u00a0sexo\u00a0a tutipl\u00e9n. Su principal objetivo amoroso \u2013pero no el \u00fanico\u2013 era\u00a0Clodia, casada con el maduro gobernador de la galia\u00a0Quinto Cecilo Metelo C\u00e9ler, y&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":2423,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3],"tags":[],"class_list":["post-2440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sexo"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[1],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"_links":{"self":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts\/2440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/comments?post=2440"}],"version-history":[{"count":1,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts\/2440\/revisions"}],"predecessor-version":[{"id":2441,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts\/2440\/revisions\/2441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/media\/2423"}],"wp:attachment":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/media?parent=2440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/categories?post=2440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/tags?post=2440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}