{"id":729,"date":"2024-07-23T20:50:54","date_gmt":"2024-07-23T18:50:54","guid":{"rendered":"https:\/\/bitacoraenlared.es\/chicas\/?p=729"},"modified":"2024-08-04T21:04:33","modified_gmt":"2024-08-04T19:04:33","slug":"de-pixeles-a-billetes-23-cosas-que-los-sims-me-han-ensenado-sobre-el-dinero","status":"publish","type":"post","link":"https:\/\/bitacoraenlared.es\/chicas\/de-pixeles-a-billetes-23-cosas-que-los-sims-me-han-ensenado-sobre-el-dinero\/","title":{"rendered":"De p\u00edxeles a billetes: 23 cosas que Los Sims me han ense\u00f1ado sobre el dinero"},"content":{"rendered":"<p>Juego a <a title=\"Los Sims 4\" href=\"https:\/\/www.hobbyconsolas.com\/videojuegos\/sims-4\" target=\"_blank\" rel=\"noopener\"><em>Los<\/em> <em>Sims<\/em><\/a> desde que ten\u00eda 5 a\u00f1os. He tenido todas y cada una de sus <a title=\"Trucos Los Sims 4 y expansiones\" href=\"https:\/\/www.hobbyconsolas.com\/guias-trucos\/sims-4\/trucos-sims-4-expansiones-todos-trucos-claves-codigos-pc-ps4-xbox-one-2021-545833\" target=\"_blank\" rel=\"noopener\">expansiones<\/a> (y nunca utilizo <a title=\"Mejores mods gratis de Los Sims 4 en 2023\" href=\"https:\/\/www.hobbyconsolas.com\/guias-trucos\/sims-4\/mejores-mods-gratis-sims-4-2023-1244352\" target=\"_blank\" rel=\"noopener\"><em>mods<\/em><\/a>, extensiones que modifican el contenido original).<\/p>\n<p>A d\u00eda de hoy, me puedo pasar horas y horas construyendo casas, eligiendo c\u00f3mo quiero vestir a mi Sim para cada estaci\u00f3n del a\u00f1o y desarrollando su historia por generaciones. Pero me cuesta mucho m\u00e1s apagar el ordenador y olvidarme de la vida de mi personaje para seguir con la m\u00eda.<\/p>\n<p>A veces hasta <strong>juego a <\/strong><em><strong>Los Sims<\/strong><\/em><strong> para buscar inspiraci\u00f3n (y esta es una de ellas)<\/strong>.<\/p>\n<p>No tengo conciencia de todas las cosas que <em>Los Sims<\/em> me han ense\u00f1ado en estos 20 a\u00f1os \u2014seguramente, hasta el significado del <a title=\"Las cosas m\u00e1s deshonrosas y cuestionables que puedes hacer en Los Sims\" href=\"https:\/\/www.hobbyconsolas.com\/listas\/cosas-deshonrosas-cuestionables-puedes-hacer-sims-621569\"><em>\u00f1iqui \u00f1iqui<\/em><\/a>\u2014. Aunque s\u00ed tengo una muy clara: el dinero. Que las cosas ten\u00edan un precio, que necesitas un trabajo para conseguirlo (que costaba mucho esfuerzo) y que, con el paso del tiempo y la ampliaci\u00f3n de la familia, m\u00e1s complicado se hac\u00eda.<\/p>\n<p><em>Nota para el lector con expertise: por supuesto, <\/em><a title=\"Por qu\u00e9 la familia es crucial en la educaci\u00f3n financiera\" href=\"https:\/\/www.businessinsider.es\/familia-crucial-educacion-financiera-1133023\"><em>mi familia ha sido mi primer influencer<\/em><\/a><em>, pero eso no quita que el juego haya dejado huella y que a d\u00eda de hoy me encuentre muchas veces pensando en m\u00ed misma como un ser inanimado que tiene que resolver un problema que ya ha visto antes.\u00a0<\/em><\/p>\n<p>Con este tel\u00f3n de fondo, he recopilado todas aquellas <strong>ideas que <\/strong><em><strong>Los Sims 4<\/strong><\/em><strong> y versiones anteriores de la saga podr\u00edan haberme dado sobre el dinero y el \u00e9xito<\/strong>.<\/p>\n<h2>1. El dinero definitivamente ayuda a ser feliz, pero sigue sin ser suficiente<\/h2>\n<p>Tener dinero en <em>Los Sims<\/em> y <a title=\"H\u00e1bitos para ganar dinero y generar riqueza, seg\u00fan expertos\" href=\"https:\/\/www.businessinsider.es\/habitos-ganar-dinero-generar-riqueza-expertos-1149711\">en la vida real es una preocupaci\u00f3n menos<\/a>. Dir\u00eda que no mucho m\u00e1s, pero lo cierto es que te permite mejorar tu vida en muchos aspectos (que veremos m\u00e1s adelante).<\/p>\n<p>En otras palabras, <strong>el dinero compra parte de la felicidad<\/strong>. Ahora bien, sigues teniendo unas necesidades que cubrir, unas emociones a las que prestar especial atenci\u00f3n y un estilo de vida que puede acabar condicionando la forma en la que act\u00faas en tu d\u00eda a d\u00eda (como <a title=\"5 se\u00f1ales de que eres adicto al trabajo\" href=\"https:\/\/www.businessinsider.es\/senales-eres-adicto-trabajo-1020573\">los adictos al trabajo<\/a>).<\/p>\n<h2>2. Ser autodidacta puede ahorrar mucho dinero<\/h2>\n<p>Asistir a una clase particular en <em>Los Sims<\/em> te cuesta 250 simoleones (la moneda del sistema de juego). Un plato de chili de verduras, unos 10 simoleones. Y que venga alguien a tu casa a arreglarte el v\u00e1ter, unos 100 simoleones.<\/p>\n<p>Si te vas a la <a title=\"5 bibliotecas en las que perder\u00e1s la noci\u00f3n del tiempo\" href=\"https:\/\/www.businessinsider.es\/estas-5-librerias-demuestran-templos-libros-896609\">biblioteca<\/a> o investigas en internet todo esto puede salirte gratis. \u00a1Y hasta puedes ganar dinero con ello! La jardiner\u00eda, por ejemplo, es un buen <a title=\"18 formas de ganar un dinero extra en 2023\" href=\"https:\/\/www.businessinsider.es\/18-formas-ganar-dinero-extra-2023-1168508\">hobby para conseguir unos ingresos extra<\/a>. A d\u00eda de hoy, no vendo mis cosechas para ganar dinero, pero s\u00ed aprendo<strong> nuevas habilidades por mi cuenta para ahorrar m\u00e1s en casa<\/strong>.<\/p>\n<h2>3. Las habilidades (hasta las <em>soft skills<\/em>) son muy importantes para el desarrollo personal y profesional<\/h2>\n<p>Desarrollar tus <a title=\"6 habilidades sociales que no pueden faltar en tu curr\u00edculum\" href=\"https:\/\/www.businessinsider.es\/6-habilidades-sociales-no-pueden-faltar-curriculum-1000993\">habilidades tambi\u00e9n te permitir\u00e1 ascender m\u00e1s r\u00e1pido<\/a> en el trabajo, en <em>Los Sims<\/em> y en la vida real.\u00a0<strong>Seg\u00fan tu carrera profesional, necesitar\u00e1s potenciar unas m\u00e1s que otras<\/strong>. Por ejemplo, si quieres ser astronauta, la comedia no te servir\u00e1 para mucho. Pero la l\u00f3gica, la destreza manual y algo de carisma seguramente te abra muchas puertas.<\/p>\n<p>Adem\u00e1s, cualquier habilidad que desarrolles te servir\u00e1 para sacar temas de conversaci\u00f3n m\u00e1s interesantes, hacer <a title=\"11 trabajos a tiempo parcial por los que pagan realmente\" href=\"https:\/\/www.businessinsider.es\/11-trabajos-tiempo-parcial-pagan-realmente-bien-959879\">trabajos espor\u00e1dicos muy bien pagados<\/a> por s\u00f3lo unas horas y hacer de mentor a otras personas (sobre todo a tus hijos).<\/p>\n<h2>4. Las compras de segunda mano no est\u00e1n nada mal para ahorrar unos simoleones (o euros)<\/h2>\n<p>En el mantenimiento podr\u00e1s ahorrarte todo el dinero que quieras (ojo, a veces no te merece la pena, que el tiempo tambi\u00e9n es oro y tienes que descansar). Pero tambi\u00e9n tienes que hacer compras para el hogar, tanto si te mudas como si en un incendio no hay manera de recuperar el objeto en cuesti\u00f3n.<\/p>\n<p><strong>Las lavadoras, las neveras y hasta las camas de segunda mano te pueden sacar de un apuro<\/strong> sin poner en riesgo el pago de las facturas. Eso s\u00ed, en cuanto entre en tu <a title=\"Si te haces un l\u00edo con el dinero y no te aclaras con lo que ganas y lo que gastas necesitas un presupuesto personal\" href=\"https:\/\/www.businessinsider.es\/teach\/aprende-crear-presupuesto-personal-manejar-mejor-finanzas-1235084\">presupuesto<\/a>, c\u00f3mprate un electrodom\u00e9stico nuevo, porque su calidad tambi\u00e9n influir\u00e1 en el resultado y en c\u00f3mo te sientes.<\/p>\n<h2>5. Alquilar una habitaci\u00f3n genera unos ingresos extras en momentos de apuro (o drena dinero sin darte cuenta)<\/h2>\n<p>En <em>Los Sims<\/em> puedes <a title=\"Airbnb: C\u00f3mo tener ingresos pasivos y ganar miles\" href=\"https:\/\/www.businessinsider.es\/airbnb-como-tener-ingresos-pasivos-ganar-miles-euros-alquilando-casas-1081667\">alquilar una habitaci\u00f3n<\/a> de tu casa sin meter en medio a tu casero. Eso te puede <strong>generar unos simoleones extras, que no te vienen nada mal <\/strong>cuando est\u00e1s empezando.<\/p>\n<p>Ahora bien, en el juego s\u00f3lo te vas a quedar con los numeritos en verde que te ingresan una vez al mes. Pero en la vida real tienes que hacer <strong>un balance de los gastos que esta persona te supone respecto a lo que ingresas<\/strong> \u2014como la factura de la luz cuando t\u00fa te vas fuera a trabajar o la del supermercado cuando se come tus platos preparados\u2014.<\/p>\n<h2>6. Generar ingresos pasivos puede ser un sobresueldo muy interesante (incluso se puede acabar viviendo de ello)<\/h2>\n<p>Ya lo mencionaba antes: <strong>cuando eres bueno en algo, en <\/strong><em><strong>Los Sims <\/strong><\/em><strong>y en la vida real puedes ganar dinero por ello<\/strong>.\u00a0Una de las v\u00edas m\u00e1s interesantes en el juego es la escritura. A medida que desarrollas la habilidad y publicas libros, vas ganando m\u00e1s y m\u00e1s dinero, hasta que consigues <em>best sellers<\/em> y haces una fortuna. Tambi\u00e9n puedes <a title=\"Los mejores programas gratis para crear videojuegos\" href=\"https:\/\/www.hobbyconsolas.com\/reportajes\/crear-videojuegos-mejores-programas-gratis-94320\">desarrollar videojuegos<\/a>.<\/p>\n<p>El alquiler es una forma de <a title=\"Las 4 mejores formas de generar ingresos pasivos sin dinero\" href=\"https:\/\/www.businessinsider.es\/4-mejores-formas-generar-ingresos-pasivos-dinero-1005517\">generar ingresos pasivos<\/a>, pero al menos en <em>Los Sims<\/em> puede traerte m\u00e1s problemas que simoleones. \u00bfCu\u00e1nto te cuesta que la novia de tu compa\u00f1era de piso venga a tu casa cuando quiera? \u00bfO que no sepa poner la lavadora y la rompa cada dos por tres?<\/p>\n<h2>7. El talento art\u00edstico o los conocimientos de programaci\u00f3n pueden ser un<em> side hustle <\/em>muy potente \u2014y generar mucho dinero\u2014<\/h2>\n<p>Puedes explotar <strong>hobbies como la pintura, la m\u00fasica o la costura <\/strong>(que se lo digan a <a title=\"We Are Knitters, la startup espa\u00f1ola que arrasa con la venta de ovillos por internet, crece un 100% en Espa\u00f1a durante el confinamiento\" href=\"https:\/\/www.businessinsider.es\/como-we-are-knitters-ha-aumentado-100-facturacion-espana-658807\">We are Knitters<\/a>). Cada cuadro, concierto o ropa de punto que vendas es un <a title=\"29 formas de ganar un dinero extra de forma f\u00e1cil y r\u00e1pida\" href=\"https:\/\/www.businessinsider.es\/ganar-dinero-extra-facil-rapido-300877\">ingreso extra<\/a>.<\/p>\n<p>As\u00ed, no tienes que dedicar tu vida a una \u00fanica actividad como los videojuegos o la escritura. Puedes hacerlo simplemente para que tu Sim se relaje y, a la vez, saque un provecho econ\u00f3mico de ello. Esto es 100% aplicable a la vida real.<\/p>\n<h2>8. Los estudios y la experiencia laboral ayudan a conseguir mejores puestos de trabajo (y sueldos m\u00e1s altos)<\/h2>\n<p>Estas mismas <strong>habilidades o haber tenido un puesto similar en el pasado<\/strong>, en <em>Los Sims<\/em> tambi\u00e9n son sin\u00f3nimo de mejores <a title=\"10 mejores apps para buscar trabajo de forma r\u00e1pida\" href=\"https:\/\/www.businessinsider.es\/10-mejores-apps-buscar-trabajo-forma-rapida-espana-1018335\">ofertas de trabajo<\/a>. En el juego, los ascensos se miden por niveles. Si no tienes ni idea, empiezas en el nivel n\u00famero uno. Pero si tienes algo de experiencia o talento, puedes empezar en el nivel tres o cinco, seg\u00fan la oferta de trabajo.<\/p>\n<p>Si, adem\u00e1s, has estudiado una carrera universitaria relacionada con la profesi\u00f3n que quieres elegir, seguramente empieces el primer d\u00eda en una rama muy superior. Hasta el nivel siete, cerca del m\u00e1ximo que ser\u00eda el nivel n\u00famero 10.<\/p>\n<h2>9. Necesitas bastante dinero de entrada para independizarte<\/h2>\n<p>En <em>Los Sims<\/em> empiezas el primer d\u00eda con unos 20.000 simoleones. Con ese dinero te puedes <a title=\"Qu\u00e9 va a pasar con la vivienda en 2023: \u00bfbuen momento?\" href=\"https:\/\/www.businessinsider.es\/va-pasar-vivienda-2023-buen-momento-comprar-casa-1271908\">comprar una casa<\/a> amueblada o sin amueblar o <a title=\"7 consejos para encontrar el mejor piso de alquiler\" href=\"https:\/\/www.businessinsider.es\/7-consejos-encontrar-mejor-piso-alquiler-848411\">alquilar un piso<\/a>, con su correspondiente <a title=\"Esto es lo m\u00e1ximo que te pueden pedir de fianza\" href=\"https:\/\/www.businessinsider.es\/maximo-te-pueden-pedir-fianza-alquilar-piso-932737\">fianza<\/a> y mobiliario.<\/p>\n<p>La gran mayor\u00eda de las veces te quedas con menos de 5.000 simoleones el primer d\u00eda. Parecen suficiente, pero con <strong>los gastos de la comida, los muebles de casa y un ordenador nuevo para poder investigar o realizar compras online, te quedas pr\u00e1cticamente a cero<\/strong>.<\/p>\n<p>En la vida real <strong>no vienes al mundo con 20.000 euros en el bolsillo<\/strong>, pero tienes que ahorrar un <a title=\"Emanciparse en 2022 si eres joven es m\u00e1s dif\u00edcil\" href=\"https:\/\/www.businessinsider.es\/emanciparse-2022-eres-joven-dificil-2008-1107875\">peque\u00f1o colch\u00f3n antes de poder irte de casa e independizarte<\/a>.<\/p>\n<h2>10. Ir a la universidad y trabajar a la vez es igual o peor que en la vida real<\/h2>\n<p>El c\u00f3ctel tareas del hogar, trabajo para poder pagar el alquiler y los gastos de la casa y 4 asignaturas por semana de una carrera universitaria en <em>Los Sims<\/em> es casi tan dif\u00edcil como en la vida real. Siempre y cuando tu objetivo sea sobrevivir al curso, aprobar y ser (m\u00ednimamente) feliz.<\/p>\n<p>En este \u00faltimo punto es donde est\u00e1 la clave: sigues teniendo unas necesidades sociales y de entretenimiento que tienes que cubrir. Si no las atiendes, <strong>tu Sim se deprime, se estresa y se bloquea<\/strong>. Entonces, <strong>obtiene peores resultados en general<\/strong>. No s\u00e9 a ti, pero a m\u00ed me pasa exactamente igual.<\/p>\n<h2>11. El tiempo fuera de la jornada laboral es oro, pero s\u00f3lo se puede aprovechar si uno est\u00e1 a gusto con el trabajo<\/h2>\n<p>A simple vista, el trabajo en <em>Los Sims<\/em> parece simplemente un tr\u00e1mite. T\u00fa mandas a tu Sim a cumplir con su <a title=\"Jornada laboral no lineal: as\u00ed puedes ser m\u00e1s productivo\" href=\"https:\/\/www.businessinsider.es\/jornada-laboral-no-lineal-puedes-ser-productivo-1202200\">jornada laboral<\/a> (ocho horas, si no quieres hacer horas extra); haces que el tiempo pase r\u00e1pido para que vuelva pronto y pueda, \u00a1por fin!, seguir con su vida.<\/p>\n<p>Cuando llega a casa tiene que cubrir sus necesidades, potenciar las habilidades para ascender en el trabajo y descansar. \u00bfQu\u00e9 pasa cuando tu Sim es infeliz en el trabajo? Que cuando llega a casa lo \u00faltimo que quiere es seguir haciendo cosas.<\/p>\n<p>Con lo que, <strong>si haces un trabajo que te gusta no s\u00f3lo ganas dinero, sino que ser\u00e1s un poquito m\u00e1s feliz, te sentir\u00e1s m\u00e1s realizado y podr\u00e1s seguir <\/strong>prosperando en la vida profesional y personal.<\/p>\n<h2>12. Montar tu propio negocio es otro nivel<\/h2>\n<p>De alguna forma podr\u00eda decir que <em>Los Sims 4<\/em> me ense\u00f1aron la vida del aut\u00f3nomo con todo detalle. Pero, despu\u00e9s de vivirlo en primera persona, s\u00e9 que es infinitamente m\u00e1s complicada en la vida real.<\/p>\n<p>Ahora bien, la cantidad de dinero que tienes que <a title=\"30 ideas de negocios para emprendedores\" href=\"https:\/\/www.businessinsider.es\/30-ideas-negocios-emprendedores-pueden-ser-muy-rentables-1056367\">ahorrar para abrir tu propio negocio<\/a> (en este caso un restaurante, por m\u00e1s de 40.000 simoleones), las transferencias entre la unidad familiar y el negocio, el coste de los empleados, la publicidad y el propio servicio podr\u00edan formar un juego totalmente independiente del universo de <em>Los Sims<\/em>.<\/p>\n<h2>13. Los contactos son realmente importantes, aunque en unas profesiones m\u00e1s que en otras<\/h2>\n<p>La gran mayor\u00eda de las ocasiones (a no ser que seas alguien muy sociable) no te dar\u00e1s cuenta en tu d\u00eda a d\u00eda de que te hace falta una buena charla. <em>Los Sims<\/em> de alguna forma me han servido de recordatorio. Tambi\u00e9n para empapar de ese carisma el espacio de trabajo.<\/p>\n<p>Mantener una <a title=\"9 perfiles de compa\u00f1eros que puedes encontrarte\" href=\"https:\/\/www.businessinsider.es\/9-perfiles-companeros-puedes-encontrarte-trabajo-1162748\">buena relaci\u00f3n con tus compa\u00f1eros de trabajo<\/a>, hacer amigos por toda la ciudad y conocer hasta a los dependientes de los puestos del barrio te puede llevar muy alto en cualquier realidad, tambi\u00e9n en la virtual. Unos <strong>impulsar\u00e1n tu ascenso o te dar\u00e1n un toque cuando encuentren un puesto que mejor se adapte a ti<\/strong> y los otros te har\u00e1n saber de los mejores descuentos disponibles.<\/p>\n<h2>14. La fama atrae el dinero, pero roba el alma<\/h2>\n<p><em>Los Sims<\/em> famosos tambi\u00e9n sufren la presi\u00f3n de la fama. \u00abEst\u00e1s a punto de perder una estrella\u00bb, se lee en la notificaci\u00f3n. Y de repente se pone tenso, triste o enfadado. Tienes que hacer alg\u00fan trabajo que haga que todos hablen de ti de nuevo, salir por la ciudad y hacerte fotos con tus fans o estar en <a title=\"El negocio del 'streaming' tiene un problema de rentabilidad\" href=\"https:\/\/www.businessinsider.es\/negocio-streaming-tiene-problema-rentabilidad-1191032\"><em>streaming<\/em> las 24 horas del d\u00eda<\/a>.<\/p>\n<p>Claro, cuando eres famoso nadas en dinero. Todas las puertas se abren ante ti. Y todo el mundo quiere darte un abrazo. Pero esto <strong>tambi\u00e9n sucede cuando tienes una buena reputaci\u00f3n, haces voluntariados, das buenos consejos a otros Sims<\/strong> y eres respetuoso con el medioambiente.\u00a0As\u00ed que, <strong>qui\u00e9n quiere la fama si puede tener una buena reputaci\u00f3n<\/strong> en un entorno m\u00e1s controlado.<\/p>\n<h2>15. El tipo de inter\u00e9s en tu contra<\/h2>\n<p>En <em>Los Sims 4 <\/em>tambi\u00e9n puedes <strong>pedir pr\u00e9stamos a otros sims o al propio \u00absistema\u00bb de juego<\/strong>. En este \u00faltimo caso, se trata de un pr\u00e9stamo estudiantil para poder ir a la universidad que viene, como en la vida real, con sus propios <a title=\"Qu\u00e9 son los intereses y qu\u00e9 tipos de inter\u00e9s existen\" href=\"https:\/\/www.businessinsider.es\/que-es\/intereses-1177642\">intereses<\/a>.<\/p>\n<p>En el ejemplo de la imagen anterior, el sim tiene que abonar 186 simoleones por la matr\u00edcula y el alojamiento universitario. Si no tiene ese dinero y necesita un pr\u00e9stamo, tendr\u00e1 entonces que asumir un inter\u00e9s y terminar pagando 195 simoleones en total.<\/p>\n<h2>16. La calidad de los objetos puede tener un impacto en el bienestar (incluso para el Sim m\u00e1s frugal del planeta)<\/h2>\n<p>Aunque seas un Sim viviendo en el modo \u00absin servicios\u00bb (un ajuste del juego que te obliga a vivir sin suministros b\u00e1sicos como la electricidad o el agua en tu unidad dom\u00e9stica), un buen sof\u00e1 te har\u00e1 disfrutar m\u00e1s de una siesta que una toalla en la playa de Sulani.<\/p>\n<p>La <strong>calidad de los objetos de casa hacen que el Sim se sienta mejor, m\u00e1s c\u00f3modo o seguro<\/strong>. \u00bfA qui\u00e9n no le pasa esto? De alguna forma te hace pensar que merece la pena pagar m\u00e1s por algunos objetos del hogar, sobre todo los de descanso y los de cocina.<\/p>\n<h2>17. Cuantas m\u00e1s cosas se tienen en propiedad, m\u00e1s hay que pagar por arreglos (a no ser que haya un manitas en casa)<\/h2>\n<p>Si la destreza manual no es lo tuyo y llegas justo a fin de mes, no te conviene hacer grandes compras o estar\u00e1s con el inodoro robot soltando agua por el v\u00e1ter durante toda la semana.<\/p>\n<h2>18. \u00a1Y m\u00e1s sale a pagar en las facturas del hogar!<\/h2>\n<p>Adem\u00e1s, has de tener en cuenta que, <strong>cuantas m\u00e1s cosas tienes en casa, m\u00e1s tienes que pagar en las facturas del hogar<\/strong>. La cantidad aumentar\u00e1 o se moderar\u00e1 seg\u00fan el uso que hagas de los electrodom\u00e9sticos o de las fuentes de agua, como el fregadero o la ba\u00f1era.<\/p>\n<p>Pero como si fuese a modo de impuesto, hasta una escultura puede aumentar lo que te cuesta el alquiler de tu casa. Has le\u00eddo bien. Este es un <a title=\"Patrimonio o impuesto a las grandes fortunas\" href=\"https:\/\/www.businessinsider.es\/diferencias-impuesto-patrimonio-grandes-fortunas-649261\">tipo impositivo a los ricos<\/a>.<\/p>\n<h2>19. Ahorrar es m\u00e1s que tener dinero para comprar lo que quieres<\/h2>\n<p>Cuanto dinero ingresaba en <em>Los Sims<\/em>, tanto me quer\u00eda gastar. A veces esperaba al siguiente sueldo para comprar cualquier objeto de ocio o de decoraci\u00f3n. Pero estos peque\u00f1os caprichos <strong>retrasaban otros lujos m\u00e1s importantes en la vida de un sim como las vacaciones o las reformas en el hogar<\/strong>.<\/p>\n<p>Para m\u00e1s, cuando alg\u00fan electrodom\u00e9stico se estropeaba, quer\u00eda ampliar la familia o simplemente montar una fiesta en casa y no ten\u00eda nada ahorrado, el juego se complicaba. De alguna manera <em>Los Sims<\/em> me ense\u00f1aron que todo lo que ganaba no lo pod\u00eda gastar en el momento.<\/p>\n<h2>20. Tener alarmas \u2014seguros del hogar\u2014 ahorra una reforma entera en la cocina (o morir)<\/h2>\n<p>Todav\u00eda no poseo mi propia casa, pero algo que me ha quedado claro jugando a <em>Los Sims<\/em> es que una alarma de incendios es imprescindible. No s\u00f3lo por lo caro que te puede costar renovar los muebles de la habitaci\u00f3n, sino porque puedes morir sin que te d\u00e9 tiempo a reaccionar.<\/p>\n<p><em>Los Sims 4<\/em> ya no tienen ladrones que entran a hurtadillas en tu casa y se llevan tu televisi\u00f3n, tu jacuzzi o tu telescopio de la terraza. Pero antes tambi\u00e9n era imprescindible tener una alarma antirrobo cerca de la puerta del hogar, porque <strong>el agujero que pod\u00edan dejar en tu bolsillo era importante<\/strong>.<\/p>\n<h2>21. Nunca se pierde la esperanza de que una t\u00eda muy lejana deje una gran herencia<\/h2>\n<p>He hecho todas las cavilaciones posibles relacionadas con una posible herencia de una t\u00eda muy, muy lejana. Y no, no creo que vaya a recibir ninguna en lo que me queda de vida. Pero Los Sims me han ense\u00f1ado que un d\u00eda te llama un desconocido, te hace una broma y contestando como si fuese Pablo Motos en directo desde el Hormiguero, te da 2.500 simoleones para seguir con tu vida.<\/p>\n<p>As\u00ed que, si todav\u00eda te queda alguna esperanza, cons\u00e9rvala (que no te cuesta nada).<\/p>\n<h2>22. Los hijos son un agujero de dinero (y tiempo) sin fondo<\/h2>\n<p>Antes de continuar con este punto, he de admitir que no me gusta mucho jugar con grandes familias en <em>Los Sims<\/em>. Soy m\u00e1s de pasar mucho tiempo construyendo, jugando con un Sim al que le cojo mucho cari\u00f1o y decepcion\u00e1ndome con las siguientes generaciones.<\/p>\n<p>Las pocas veces que he jugado con familias en <em>Los Sims<\/em> he terminado, de alguna manera, renunciando a seguir con sus vidas. Con esto quiero decir que he dejado de jugar con ellos, no que los haya metido en la piscina, quitado las escaleras y puesto una barandilla.<\/p>\n<p><strong>Mantener un estilo de vida equilibrado, darles una buena educaci\u00f3n y ayudarles a continuar con sus vidas es muy complicado (y caro)<\/strong>. Todos no pueden ser felices a la vez sin que utilices un truco de vez en cuando, tengas sirvientes o uno se quede de amo de casa. Pero, a su vez, te ense\u00f1a muchas cosas de lo que implica y<strong> lo importante que es dedicar recursos a la familia<\/strong>.<\/p>\n<h2>23. Es necesario un equilibrio entre lo profesional y lo personal si quieres formar una bonita familia<\/h2>\n<p>Entonces, cuando decido finalmente crear una familia en <em>Los Sims<\/em>, normalmente <strong>me aseguro de que los progenitores (sean pareja o solteros) tengan una vida estable y encaminada<\/strong> y que dediquen <a title=\"Por qu\u00e9 la familia es crucial en la educaci\u00f3n financiera\" href=\"https:\/\/www.businessinsider.es\/familia-crucial-educacion-financiera-1133023\">muchos recursos<\/a> y tiempo a la <a title=\"3 errores m\u00e1s comunes que se cometen al educar a los hijos\" href=\"https:\/\/www.businessinsider.es\/3-errores-comunes-cometen-educar-hijos-1010045\">educaci\u00f3n de sus hijos<\/a>.<\/p>\n<p>De nuevo, como cuando los turnos de trabajo empezaron a tener realmente relevancia en la vida de <em>Los Sims<\/em>, la gratificaci\u00f3n de tener una familia en tu vida que te complemente y te ayude a cubrir todas esas necesidades que, con y sin dinero est\u00e1n ah\u00ed, merece mucho la pena.<\/p>\n<p><a href=\"https:\/\/www.businessinsider.es\/\"><em>Kamila Barca<\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juego a Los Sims desde que ten\u00eda 5 a\u00f1os. He tenido todas y cada una de sus expansiones (y nunca utilizo mods, extensiones que modifican el contenido original). A d\u00eda de hoy, me puedo pasar horas y horas construyendo casas, eligiendo c\u00f3mo quiero vestir a mi Sim para cada estaci\u00f3n del a\u00f1o y desarrollando su&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":703,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[1],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"_links":{"self":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts\/729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/comments?post=729"}],"version-history":[{"count":2,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts\/729\/revisions"}],"predecessor-version":[{"id":731,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts\/729\/revisions\/731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/media\/703"}],"wp:attachment":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/media?parent=729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/categories?post=729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/tags?post=729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}