{"id":795,"date":"2024-09-02T18:34:19","date_gmt":"2024-09-02T16:34:19","guid":{"rendered":"https:\/\/bitacoraenlared.es\/chicas\/?p=795"},"modified":"2024-09-01T18:40:08","modified_gmt":"2024-09-01T16:40:08","slug":"asi-se-la-ha-jugado-trump-a-elon-musk","status":"publish","type":"post","link":"https:\/\/bitacoraenlared.es\/chicas\/asi-se-la-ha-jugado-trump-a-elon-musk\/","title":{"rendered":"As\u00ed se la ha jugado Trump a Elon Musk"},"content":{"rendered":"<p>Nadie se ha arrastrado por Donald Trump tanto como lo ha hecho Elon Musk.<\/p>\n<p>Bien es cierto que\u00a0<strong>Musk lleva tiempo carg\u00e1ndose su imagen de multimillonario altruista<\/strong>\u00a0a lo Tony Stark, concretamente desde que\u00a0<a href=\"https:\/\/www.businessinsider.com\/elon-musk-business-playbook-boss-visionary-jerk-spacex-tesla-twitter-2022-12\" rel=\"nofollow\">compr\u00f3 Twitter<\/a>\u00a0y\u00a0<a title=\"La 'zombificaci\u00f3n' de Twitter: Musk ha condenado a la red social a un destino peor que la muerte\" href=\"https:\/\/www.businessinsider.es\/elon-musk-ha-condenado-twitter-destino-peor-muerte-1274390\">lo convirti\u00f3 en una Casa Mojo Dojo<\/a>\u00a0(como hace Ken en la pel\u00edcula de\u00a0<a title=\"Cr\u00edtica de Barbie: brillante deconstrucci\u00f3n del heteropatriarcado sin renunciar al humor\" href=\"https:\/\/www.hobbyconsolas.com\/reviews\/critica-barbie-brillante-deconstruccion-heteropatriarcado-1277796\" target=\"_blank\" rel=\"noopener\"><em>Barbie<\/em><\/a><em>\u00a0<\/em>al imponer su visi\u00f3n machista) de extrema derecha. Pero ha sido su aduladora charla con Trump lo que ha rematado el asunto.<\/p>\n<p>El hombre que afirmaba que sus principales objetivos eran salvar a la humanidad,\u00a0<a href=\"https:\/\/www.businessinsider.com\/free-speech-elon-musk-wants-would-be-terrible-2023-12\" rel=\"nofollow\">defender la libertad de expresi\u00f3n<\/a>\u00a0y guiar al mundo hacia un futuro mejor\u00a0<strong>se mostr\u00f3 como un perro faldero m\u00e1s<\/strong>, degrad\u00e1ndose de una forma muy torpe ante el pol\u00edtico para servir a su riqueza.<\/p>\n<p>Y no es el \u00fanico que ha destruido su imagen p\u00fablica al arrimarse a Trump. Al igual que Musk, que ha comprometido 45 millones de d\u00f3lares al mes a la campa\u00f1a del expresidente (unos 40,7 millones de euros),\u00a0<strong>otros multimillonarios han recaudado y donado grandes sumas para el Donald Trump<\/strong>. Pero la diferencia es que otros no permiten que los humille p\u00fablicamente. A esas situaciones se exponen solo los que buscan un beneficio evidente o quieren unirse a su administraci\u00f3n.<\/p>\n<p>En otras palabras, quienes quieren sacar provecho del poder pol\u00edtico comienzan a quemar su imagen p\u00fablica una vez lo han conseguido. Pero Musk se ha adelantado a los acontecimientos.<\/p>\n<p>Tras ver la charla del otro d\u00eda, en la que el ego de Trump se impon\u00eda a cualquier cosa que pudiera decir Musk, nadie en un radio de miles de kil\u00f3metros de Mar-a-Lago [residencia privada de Trump] cree que pueda seguir subido al carro de Trump. Nadie excepto el propio Musk, que parece estar en Marte (pol\u00edticamente hablando).<\/p>\n<p>Al comienzo de la charla,\u00a0<strong>el CEO de Tesla dijo que su intenci\u00f3n era dar a los estadounidenses la oportunidad de conocer a Trump<\/strong>, como si este no hubiese sido ya presidente. Como si Musk tuviera el poder medi\u00e1tico necesario para arrojar nueva luz sobre Trump. Coment\u00f3 adem\u00e1s que quer\u00eda permitir a Trump hablar en un entorno seguro, como si no celebrara m\u00edtines una vez por semana.<\/p>\n<p>Una entrevista de este tipo pod\u00eda tener sentido en el 2015. Nueve a\u00f1os despu\u00e9s, se puede afirmar con seguridad que todo el mundo sabe lo que representa. De hecho, otros donantes ricos de Trump se est\u00e1n preguntando por qu\u00e9 est\u00e1n donando dinero a un candidato que\u00a0<a href=\"https:\/\/www.businessinsider.com\/which-billionaires-support-donald-trump-campaign\" rel=\"nofollow\">ya est\u00e1 tan \u00abbien definido\u00bb<\/a>. Y entonces entra Musk en escena, que se ha acercado a la pol\u00edtica con la misma ingenuidad que los pioneros en cripto, que trataron de reinventar las finanzas, sin saber que todo lo que estaban haciendo ya se hab\u00eda hecho.<\/p>\n<blockquote><p>Quienes quieren sacar provecho del poder pol\u00edtico comienzan a quemar su imagen p\u00fablica una vez lo han conseguido. Pero Musk se ha adelantado a los acontecimientos<\/p><\/blockquote>\n<p>En la pr\u00e1ctica, el chapucero evento de Musk\u00a0<a title=\"Elon Musk y Donald Trump han hablado en directo durante m\u00e1s de dos horas en X (Twitter), en una entrevista marcada por las dificultades t\u00e9cnicas\" href=\"https:\/\/www.businessinsider.es\/elon-musk-donald-trump-han-hablado-directo-durante-dos-horas-x-twitter-entrevista-marcada-dificultades-tecnicas-1400000\">se sald\u00f3 con 45 minutos de fallos t\u00e9cnicos<\/a>\u00a0antes incluso de que comenzara su conversaci\u00f3n con Trump. Y entonces Elon comenz\u00f3 a quemar su reputaci\u00f3n. Durante las dos horas y siete minutos que dur\u00f3 la conversaci\u00f3n, Trump se dedic\u00f3 a pisotear una y otra vez los valores que construyeron\u00a0<a href=\"https:\/\/www.businessinsider.com\/elon-musk-super-fired-up-help-biden-fight-climate-change-2021-1\" rel=\"nofollow\">la marca Musk<\/a>.<\/p>\n<p>Cuando el expresidente afirm\u00f3 que la mayor amenaza para la humanidad no era la crisis clim\u00e1tica (en parte porque proporcionar\u00eda a los humanos m\u00e1s propiedades frente al mar), Musk respondi\u00f3 con un \u00abde acuerdo\u00bb. Cabr\u00eda pensar que el hombre que en 2016 dijo que los ciudadanos deb\u00edan \u00abrebelarse\u00bb contra la industria de los combustibles f\u00f3siles y denunci\u00f3 sus subvenciones gubernamentales tendr\u00eda m\u00e1s que decir al respecto.<\/p>\n<div data-piano-position=\"entreparrafos1\"><\/div>\n<p>Pero no. Lo que hizo\u00a0<strong>Musk fue pedir a la audiencia que no demonizara a la industria del petr\u00f3leo y el gas<\/strong>\u00a0e insisti\u00f3 en que el clima pod\u00eda esperar. Solo despu\u00e9s de una hora y media, cuando Trump empez\u00f3 con sus rancias y desquiciadas divagaciones racistas, Elon ofreci\u00f3 una endeble defensa de la realidad de la emergencia clim\u00e1tica.<\/p>\n<p>El CEO de Tesla\/SpaceX\/X qued\u00f3 fatal ante Trump hablando de su tema principal, y despu\u00e9s el expresidente tom\u00f3 el control de la charla, llevando a Musk a airear algunas de sus opiniones m\u00e1s extra\u00f1as.<\/p>\n<p>Elogi\u00f3 a Trump por no silenciar a los medios de comunicaci\u00f3n durante su mandato, como si la libertad de prensa fuera algo que un presidente otorga amablemente a los ciudadanos estadounidenses a su discreci\u00f3n. Coment\u00f3 tambi\u00e9n que quiere deshacerse del Departamento de Educaci\u00f3n, y adem\u00e1s ofreci\u00f3 una defensa de las energ\u00edas renovables que sonaba delirante.<\/p>\n<p>\u00abHiroshima y Nagasaki fueron bombardeadas, pero ahora vuelven a ser ciudades llenas\u00bb, dijo Musk mientras argumentaba ante Trump las bondades de la energ\u00eda nuclear. \u00abEso es genial\u00bb, respondi\u00f3 Trump, aburrido.<\/p>\n<p>Evidentemente, el objetivo de esta charla y de todo\u00a0<strong>el apoyo que el CEO de Tesla est\u00e1 dando a Trump<\/strong>, es que este apoye su agenda pol\u00edtica, sobre todo la desregulaci\u00f3n que permite a las empresas de Musk hacer lo que quieran mientras reciben grandes subvenciones del Gobierno para sus proyectos. Est\u00e1 claro que el robusto libertario necesita algo de Washington, o no lo estar\u00eda pidiendo.<\/p>\n<p>Ha admitido p\u00fablicamente que quiere acabar con las regulaciones clim\u00e1ticas de Estados Unidos para desincentivar a los grandes fabricantes de autom\u00f3viles a fabricar veh\u00edculos el\u00e9ctricos y\u00a0<a title=\"La gran cuota de mercado de los coches el\u00e9ctricos de Tesla nunca fue sostenible\" href=\"https:\/\/www.businessinsider.es\/gran-cuota-mercado-coches-electricos-tesla-nunca-fue-sostenible-1395906\">mantener el dominio de Tesla en el mercado<\/a>. No obstante, cada vez que Musk intentaba que Trump respaldara esta \u00e9tica de \u00abayuda para m\u00ed pero no para el resto\u00bb durante la charla del lunes, fue ignorado. Musk no parece solo dispuesto a gastar mucho dinero para salirse con la suya, sino que tambi\u00e9n se prostituye por ello.<\/p>\n<p>Definitivamente, no fue exactamente el tipo de discurso que uno querr\u00eda o\u00edr de alguien cuyo objetivo (declarado) es salvar a la humanidad. El insensible y falso intelectualismo de Musk sol\u00eda ser algo que apreciaban solo aquellos muy conectados a Internet; ahora, su implicaci\u00f3n con Trump lo ha hecho evidente para todo el mundo.<\/p>\n<p>Al parecer, sus valores pol\u00edticos se reducen a votar a un candidato que detesta la prensa libre y quiere \u00abperforar, nene, perforar\u00bb. Antes, Musk sol\u00eda hablar mucho de la urgencia de la crisis clim\u00e1tica de la Tierra. Esto atrajo miles de millones en inversiones para sus proyectos tanto en los mercados privados como p\u00fablicos. Ahora parece que no iba realmente en serio; al menos, no si va en serio lo de Trump. Mucha gente rica y poderosa, como el multimillonario petrolero Harold Hamm, tienen claro por qu\u00e9 apoyan a Trump, y ahora queda claro que Musk no es diferente. Nunca lo fue.<\/p>\n<h2>Est\u00fapido Soros<\/h2>\n<p><strong>Los intentos de Musk de utilizar a Trump para su beneficio personal<\/strong>\u00a0no son su \u00fanico intento de introducirse en la pol\u00edtica electoral. Seg\u00fan los primeros resultados de estos otros esfuerzos, no parece tener m\u00e1s \u00e9xito en influir en la microescala de la pol\u00edtica que en trabajar en los pasillos sagrados del poder.<\/p>\n<p>Finalmente, el activismo pol\u00edtico de Musk ha sido un fracaso, seg\u00fan un reciente reportaje de\u00a0<em>The Wall Street Journal<\/em>. Su objetivo declarado era hacer una campa\u00f1a recaudatoria para registrar a unos 800.000 nuevos votantes que, en teor\u00eda, impulsar\u00edan a Trump. Elon recurri\u00f3 a Joe Lonsdale, empresario de Silicon Valley, en abril para empezar a recaudar fondos. La propuesta de Lonsdale a los posibles donantes era que, si aportaban algo de dinero para poner en marcha la campa\u00f1a, un benefactor rico y an\u00f3nimo (Musk) se encargar\u00eda de financiar el movimiento y garantizar su \u00e9xito tras el lanzamiento.<\/p>\n<p>Despu\u00e9s, Musk contrat\u00f3 a Denis Calabrese, un consultor del Partido Republicano que en su d\u00eda fue condenado a 18 meses de c\u00e1rcel por evasi\u00f3n de impuestos y enfrent\u00f3 un juicio mientras trabajaba en otro comit\u00e9 de acci\u00f3n pol\u00edtica por acusaciones de haber recibido sobornos de proveedores. El asunto se resolvi\u00f3 extrajudicialmente.<\/p>\n<p>Cuando los esfuerzos de Calabrese por Musk no dieron sus frutos (sin mencionar de las investigaciones de dos gobiernos estatales), fue despedido en julio y sustituido por hombres que trabajaban para el gobernador Ron DeSantis de Florida. Hasta ahora, parece que la campa\u00f1a de Musk ha logrado poca cosa m\u00e1s all\u00e1 de crear una web defectuosa y recopilar algunos datos de posibles votantes indecisos. El\u00a0<em>WSJ\u00a0<\/em>public\u00f3 que ni siquiera hab\u00eda enviado por correo los formularios de registro de votantes.<\/p>\n<blockquote><p>La verdadera influencia pol\u00edtica, que requiere concentraci\u00f3n, dedicaci\u00f3n y organizaci\u00f3n, se le escapa<\/p><\/blockquote>\n<p>Si est\u00e1s al tanto de todo lo que pasa en el \u00abMuskiverso\u00bb, esta incompetencia no te sorprender\u00e1. El multimillonario fue estafado por 50.000 d\u00f3lares (algo m\u00e1s de 45.000 euros) en 2019 despu\u00e9s de que contratara a un delincuente para destapar trapos sucios sobre Vernon Unsworth, un buzo que rescat\u00f3 a un grupo de ni\u00f1os de una cueva en Tailandia y m\u00e1s tarde demand\u00f3 a Musk, alegando difamaci\u00f3n. Se trata del tipo de situaci\u00f3n vergonzosa que un poderoso multimillonario nunca querr\u00eda hacer p\u00fablica. Pero ahora que ha entrado en la pol\u00edtica de grandes fortunas, es inevitable que se evidencien estas cosas.<\/p>\n<p>Durante las \u00faltimas semanas, el l\u00edder de Venezuela, Nicol\u00e1s Maduro, un hombre fuerte y violento que se aferra al poder pese a todo, se ha referido a Musk como el \u00abhombre del saco capitalista\u00bb, un George Soros de derechas que est\u00e1 manipulando Venezuela a trav\u00e9s de X. Musk respondi\u00f3 diciendo que llevar\u00eda a Maduro a Guant\u00e1namo en persona, montado en un burro. Ya, claro.<\/p>\n<p>Dejando a un lado estas bromas y la propaganda autoritaria, hasta ahora, Maduro le est\u00e1 dando a Musk demasiado cr\u00e9dito.\u00a0<a title=\"Elon Musk le dio a Trump un mill\u00f3n de oyentes y Trump le dio a Musk sus mejores \u00e9xitos\" href=\"https:\/\/www.businessinsider.es\/elon-musk-dio-trump-millon-oyentes-trump-dio-musk-mejores-exitos-1400003\">La charla de Musk con Trump tuvo 1,1 millones de oyentes<\/a>\u00a0simult\u00e1neos en su mejor momento, aproximadamente un tercio de la audiencia de Fox News en horario de m\u00e1xima audiencia. Para su frustraci\u00f3n,\u00a0<strong>cuanto m\u00e1s tuitea Musk\u00a0<\/strong>(si as\u00ed es como se les llama ahora),\u00a0<strong>menos gente quiere ver sus mensajes<\/strong>.<\/p>\n<p>La verdadera influencia pol\u00edtica, que requiere concentraci\u00f3n, dedicaci\u00f3n y organizaci\u00f3n, se le escapa. Cada d\u00eda de los \u00faltimos dos a\u00f1os, Musk ha demostrado al mundo que, independientemente de la inmensidad de su riqueza, su poder se limita a tareas como azuzar a los\u00a0<em>trolls\u00a0<\/em>de Internet y molestar a los pol\u00edticos de todo el mundo. En definitiva, no es un vengador.<\/p>\n<p><a class=\"author-block_text__A5F3o\" href=\"https:\/\/www.businessinsider.es\/redaccion\/cristina-galvez\" rel=\"author\">Cristina G\u00e1lvez<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nadie se ha arrastrado por Donald Trump tanto como lo ha hecho Elon Musk. Bien es cierto que\u00a0Musk lleva tiempo carg\u00e1ndose su imagen de multimillonario altruista\u00a0a lo Tony Stark, concretamente desde que\u00a0compr\u00f3 Twitter\u00a0y\u00a0lo convirti\u00f3 en una Casa Mojo Dojo\u00a0(como hace Ken en la pel\u00edcula de\u00a0Barbie\u00a0al imponer su visi\u00f3n machista) de extrema derecha. Pero ha sido&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":796,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4],"tags":[],"class_list":["post-795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[1],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"_links":{"self":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts\/795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/comments?post=795"}],"version-history":[{"count":1,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts\/795\/revisions"}],"predecessor-version":[{"id":797,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/posts\/795\/revisions\/797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/media\/796"}],"wp:attachment":[{"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/media?parent=795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/categories?post=795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bitacoraenlared.es\/chicas\/wp-json\/wp\/v2\/tags?post=795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}